{"id":1163,"date":"2019-11-24T11:06:51","date_gmt":"2019-11-24T11:06:51","guid":{"rendered":"https:\/\/demo-themewinter.com\/turitor\/?page_id=1163"},"modified":"2020-01-05T12:11:58","modified_gmt":"2020-01-05T12:11:58","slug":"faq","status":"publish","type":"page","link":"https:\/\/demo-themewinter.com\/turitor\/faq\/","title":{"rendered":"Faq"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1163\" class=\"elementor elementor-1163\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12e9bc7 tutor-faq elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12e9bc7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e1695b\" data-id=\"1e1695b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c76d04 elementor-widget elementor-widget-turitor-title\" data-id=\"2c76d04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"turitor-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"ts-section-title title-left\">\n\t\t\t<h2 class=\"section-title \">\n\t\t\t\t\t\t\t\t\t<span class=\"sub-title\">#FAQ<\/span>\n\t\t\t\t\t\t\t\tA few frequently asked questions\t\t\t<\/h2>\n\t\t\t\t\t\t\t<i class=\"\"><\/i>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d5718d elementor-widget elementor-widget-text-editor\" data-id=\"5d5718d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Discover how to anticipate and adapt to the latest trends and digital<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f312eff elementor-widget elementor-widget-image\" data-id=\"f312eff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"519\" height=\"392\" src=\"https:\/\/demo-themewinter.com\/turitor\/wp-content\/uploads\/2020\/01\/contact_image.png\" class=\"attachment-large size-large wp-image-4088\" alt=\"\" srcset=\"https:\/\/demo-themewinter.com\/turitor\/wp-content\/uploads\/2020\/01\/contact_image.png 519w, https:\/\/demo-themewinter.com\/turitor\/wp-content\/uploads\/2020\/01\/contact_image-300x227.png 300w\" sizes=\"(max-width: 519px) 100vw, 519px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-19c8aed\" data-id=\"19c8aed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21d68ac elementor-widget elementor-widget-elementskit-accordion\" data-id=\"21d68ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a5595f08c6db\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-21d68ac\">\n                        <a href=\"#collapse-98355f76a5595f08c6db\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-98355f76a5595f08c6db\" aria-expanded=\"true\" aria-controls=\"Collapse-98355f76a5595f08c6db\">\n                            \n                            <span class=\"ekit-accordion-title\">How long is my personal free trial?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-98355f76a5595f08c6db\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-21d68ac\" data-parent=\"#accordion-6a5595f08c6db\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>When you sign up for a personal trial, you will receive 10 days and 200 minutes of viewing. If your trial is not canceled within the 10 days, the trial will convert to a paid subscription that will auto-renew until the subscription is canceled. <a href=\"#\">Click here<\/a> for more information on our trial.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-21d68ac\">\n                        <a href=\"#collapse-970d9756a5595f08c6db\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-970d9756a5595f08c6db\" aria-expanded=\"false\" aria-controls=\"Collapse-970d9756a5595f08c6db\">\n                            \n                            <span class=\"ekit-accordion-title\">Will I be charged now for a free trial?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-970d9756a5595f08c6db\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-21d68ac\" data-parent=\"#accordion-6a5595f08c6db\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-21d68ac\">\n                        <a href=\"#collapse-c25e7f96a5595f08c6db\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-c25e7f96a5595f08c6db\" aria-expanded=\"false\" aria-controls=\"Collapse-c25e7f96a5595f08c6db\">\n                            \n                            <span class=\"ekit-accordion-title\">Can I cancel anytime?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-c25e7f96a5595f08c6db\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-21d68ac\" data-parent=\"#accordion-6a5595f08c6db\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-21d68ac\">\n                        <a href=\"#collapse-56ae1b06a5595f08c6db\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56ae1b06a5595f08c6db\" aria-expanded=\"false\" aria-controls=\"Collapse-56ae1b06a5595f08c6db\">\n                            \n                            <span class=\"ekit-accordion-title\">What are Turitor business plans?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56ae1b06a5595f08c6db\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-21d68ac\" data-parent=\"#accordion-6a5595f08c6db\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-21d68ac\">\n                        <a href=\"#collapse-68223c36a5595f08c6db\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-68223c36a5595f08c6db\" aria-expanded=\"false\" aria-controls=\"Collapse-68223c36a5595f08c6db\">\n                            \n                            <span class=\"ekit-accordion-title\">Will I be charged now for a free trial?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-68223c36a5595f08c6db\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-21d68ac\" data-parent=\"#accordion-6a5595f08c6db\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-21d68ac\">\n                        <a href=\"#collapse-5be37816a5595f08c6db\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5be37816a5595f08c6db\" aria-expanded=\"false\" aria-controls=\"Collapse-5be37816a5595f08c6db\">\n                            \n                            <span class=\"ekit-accordion-title\">Can I cancel anytime?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5be37816a5595f08c6db\" class=\" collapse\" aria-labelledby=\"primaryHeading-5-21d68ac\" data-parent=\"#accordion-6a5595f08c6db\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-21d68ac\">\n                        <a href=\"#collapse-b2ab3706a5595f08c6db\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-b2ab3706a5595f08c6db\" aria-expanded=\"false\" aria-controls=\"Collapse-b2ab3706a5595f08c6db\">\n                            \n                            <span class=\"ekit-accordion-title\">What are Turitor business plans?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-b2ab3706a5595f08c6db\" class=\" collapse\" aria-labelledby=\"primaryHeading-6-21d68ac\" data-parent=\"#accordion-6a5595f08c6db\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>#FAQ A few frequently asked questions Discover how to anticipate and adapt to the latest trends and digital How long [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template\/full-width-template.php","meta":{"footnotes":""},"class_list":["post-1163","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo-themewinter.com\/turitor\/wp-json\/wp\/v2\/pages\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo-themewinter.com\/turitor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo-themewinter.com\/turitor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo-themewinter.com\/turitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo-themewinter.com\/turitor\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":0,"href":"https:\/\/demo-themewinter.com\/turitor\/wp-json\/wp\/v2\/pages\/1163\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo-themewinter.com\/turitor\/wp-json\/wp\/v2\/media?parent=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}