{"id":50,"date":"2019-01-11T06:15:28","date_gmt":"2019-01-11T06:15:28","guid":{"rendered":"http:\/\/localhost\/panel\/xpeedstudio\/wp\/automobil\/?page_id=50"},"modified":"2019-02-11T07:29:13","modified_gmt":"2019-02-11T07:29:13","slug":"faq","status":"publish","type":"page","link":"https:\/\/demo-themewinter.com\/autrics\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"50\" class=\"elementor elementor-50 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-865ae6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"865ae6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14f6efb\" data-id=\"14f6efb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4df6655 accordion elementor-widget elementor-widget-accordion\" data-id=\"4df6655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8171\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8171\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">1. Will you sand my vechile before painting it?                                  <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8171\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8171\"><div class=\"card\"><div id=\"collapseOne\" class=\"collapse show\" data-parent=\"#accordion\"><div class=\"card-body\">A wonderful serenity taken possession into entire soul like to these sweet mornings of spring which thing of existence this spot which was the main part<\/div><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8172\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8172\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2. How can I measure temperature in hyundai accent 2010, i have no temp gauge?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8172\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8172\"><div class=\"card\"><div id=\"collapseTwo\" class=\"collapse show\" data-parent=\"#accordion\"><div class=\"card-body\">A wonderful serenity taken possession into entire soul like to these sweet mornings of spring which thing of existence this spot which was the main part<\/div><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8173\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8173\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">3. Chevrolet Silverado 1500 Hybrid - hybrid transmission stator?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8173\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8173\"><div class=\"card\"><div id=\"collapseTwo\" class=\"collapse show\" data-parent=\"#accordion\"><div class=\"card-body\">A wonderful serenity taken possession into entire soul like to these sweet mornings of spring which thing of existence this spot which was the main part<\/div><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8174\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8174\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">4. Jaguar S-TYPE - how much is my car worth it is fully loaded and leather fully<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8174\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8174\"><div class=\"card\"><div id=\"collapseTwo\" class=\"collapse show\" data-parent=\"#accordion\"><div class=\"card-body\">A wonderful serenity taken possession into entire soul like to these sweet mornings of spring which thing of existence this spot which was the main part<\/div><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8175\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-8175\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">5. How can I measure temperature in hyundai accent 2010, i have no temp gauge<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8175\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-8175\"><div class=\"card\"><div id=\"collapseTwo\" class=\"collapse show\" data-parent=\"#accordion\"><div class=\"card-body\">A wonderful serenity taken possession into entire soul like to these sweet mornings of spring which thing of existence this spot which was the main part<\/div><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fdb69e elementor-widget elementor-widget-autrics-title\" data-id=\"0fdb69e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"autrics-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"title-section-area\">\n                <h2 class=\"section-title\">\n                    <span>Ask A<\/span> Question                <\/h2>\n            <\/div><!-- Section title -->\n        \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c54e4d elementor-widget elementor-widget-shortcode\" data-id=\"6c54e4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1537-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1537\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/autrics\/wp-json\/wp\/v2\/pages\/50#wpcf7-f1537-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1537\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1537-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"contact-us\">\n\t<div class=\"contactMe ts-main-form\">\n\t\t<div class=\"form-row\">\n\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-255\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text field\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"text-255\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-6\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-348\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"tel\" name=\"tel-348\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-row\">\n\t\t\t<div class=\"col-md-6\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email-540\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"email-540\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-md-6 select-item\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-465\"><select class=\"wpcf7-form-control wpcf7-select field\" aria-invalid=\"false\" name=\"menu-465\"><option value=\"Select Service\">Select Service<\/option><option value=\"Engine Diagnostics\">Engine Diagnostics<\/option><option value=\"Lube, Oil and Filters\">Lube, Oil and Filters<\/option><option value=\"Air Conditioning Evac\">Air Conditioning Evac<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-row\">\n\t\t\t<div class=\"col-md-12\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-406\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"textarea-406\"><\/textarea><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"btn-after pull-right\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary\" type=\"submit\" value=\"Send Message\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"clearfix\">\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c13dc79\" data-id=\"c13dc79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d933cc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d933cc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1386c14\" data-id=\"1386c14\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04af65a elementor-widget elementor-widget-autrics-title\" data-id=\"04af65a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"autrics-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"title-section-area title-border-none\">\n                <h3 class=\"section-title\">\n                    <span>Brand <\/span>Brochure                <\/h3>\n            <\/div><!-- Section title -->\n        \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27ca728 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"27ca728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#\">\n\t\t\t\t\t\t\t<i class=\"icon icon-download\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c549a18 elementor-widget elementor-widget-autrics-quote-carousel\" data-id=\"c549a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"autrics-quote-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div data-nav=\"\" class=\"testimonial-carousel owl-carousel\" >\n                    <div class=\"testimonial-container\">\n                <div class=\"testimonial-body\">\n                    <div class=\"testimonial-content\">\n                        <h4 class=\"service-name\">Engine Digonastic<\/h4>\n                       \n                    <\/div> <!-- Testimonial Content end -->\n                    <p> wonderful serenity taken possession  into entire soul  like to these sweet of  tence  this spot which was the main part created for  <\/p>\n                    <span class=\"quote-icon\"><i class=\"icon icon-quote1\"><\/i><\/span>\n                <\/div> <!-- Testimonial Body end -->\n                <div class=\"testimonial-footer\">\n                    \n                    <div class=\"client-info\">\n\n                        <h3 class=\"client-name\">Donald Gonzales<\/h3>\n                        <span class=\"client-desig\">CEO,apple<\/span>\n                    <\/div> <!-- Client info end -->\n                <\/div><!-- Testimonial Footer end -->\n            <\/div> <!-- Testimonial Box end -->\n            \n       <\/div> <!-- Testimonial Carousel -->\n     \n    \n    \n              \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e66de4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e66de4b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c8ad3bb\" data-id=\"c8ad3bb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ca87a0 elementor-widget elementor-widget-autrics-title\" data-id=\"2ca87a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"autrics-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"title-section-area title-border-none\">\n                <h3 class=\"section-title\">\n                    <span>On <\/span>Socials                <\/h3>\n            <\/div><!-- Section title -->\n        \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-916316e elementor-shape-circle e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"916316e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-32ff121\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-facebook\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-898c1d5\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-twitter\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-google-plus elementor-repeater-item-1a1c0d4\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Google-plus<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-google-plus\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-jsfiddle elementor-repeater-item-52a09da\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Jsfiddle<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-jsfiddle\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-f864db7\" href=\"#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-linkedin\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-84b83be elementor-widget elementor-widget-wp-widget-xs-service\" data-id=\"84b83be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-xs-service.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5>Service hour<\/h5>\t\r\n\t     <ul class=\"unstyled service-time\">\r\n\t     \t       \t                     <li>\r\n                        <span> Monday <\/span>\r\n                        <span>7.00 - 16.30<\/span>\r\n                     <\/li>\r\n                                        \t                     <li>\r\n                        <span> Tuesday<\/span>\r\n                        <span>7.00 - 16.30<\/span>\r\n                     <\/li>\r\n                                          \t                     <li>\r\n                        <span> Wednesday<\/span>\r\n                        <span>7.00 - 16.30<\/span>\r\n                     <\/li>\r\n                                          \t                     <li>\r\n                        <span> Thursday<\/span>\r\n                        <span>7.00 - 16.30<\/span>\r\n                     <\/li>\r\n                                          \t\r\n                                          <li>\r\n                        <span> Saturday <\/span>\r\n                        <span>7.00 - 16.30<\/span>\r\n                     <\/li>\r\n                     \r\n                                          <li>\r\n                        <span> Sunday <\/span>\r\n                        <span>7.00 - 16.30<\/span>\r\n                     <\/li>\r\n                     \r\n                  \r\n                  <\/ul> <!-- Service Time -->\r\n\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1. Will you sand my vechile before painting it? A wonderful serenity taken possession into entire soul like to these sweet mornings of spring which thing of existence this spot which was the main part 2. How can I measure temperature in hyundai accent 2010, i have no temp gauge? A wonderful serenity taken possession [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template\/full-width-template.php","meta":{"footnotes":""},"class_list":["post-50","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo-themewinter.com\/autrics\/wp-json\/wp\/v2\/pages\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo-themewinter.com\/autrics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo-themewinter.com\/autrics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo-themewinter.com\/autrics\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo-themewinter.com\/autrics\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":0,"href":"https:\/\/demo-themewinter.com\/autrics\/wp-json\/wp\/v2\/pages\/50\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo-themewinter.com\/autrics\/wp-json\/wp\/v2\/media?parent=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}